{"id":29869,"date":"2026-03-25T09:55:22","date_gmt":"2026-03-25T14:55:22","guid":{"rendered":"https:\/\/www.producempresarial.pe\/?p=29869"},"modified":"2026-04-13T14:57:54","modified_gmt":"2026-04-13T19:57:54","slug":"reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025","status":"publish","type":"post","link":"https:\/\/www.producempresarial.pe\/en\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/","title":{"rendered":"Report: Daily supply of hydrobiological resources. Wholesale Fish Markets 23-03-2026"},"content":{"rendered":"<p>Hoy 23 de Marzo, ingres\u00f3 560.0 TM de recursos hidrobiol\u00f3gicos a los mercados mayoristas de Lima (Villa Mar\u00eda del Triunfo) y Callao (Ventanilla); siendo 6.4% superior al abastecimiento de ayer. Entre las especies con mayor ingreso el d\u00eda de hoy fueron: Jurel, Bonito y Pota.<br>Asimismo, ingresaron 378.6 TM de recursos hidrobiol\u00f3gicos a los mercados mayoristas pesqueros de Tumbes, Piura, Lambayeque, La Libertad, \u00c1ncash, Arequipa, Ica, Tacna, Cajamarca, Loreto y Ucayali.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/RMP_23032026.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Embed of RMP_23032026.\"><\/object><a id=\"wp-block-file--media-d06fe0b0-57a8-4bac-9682-ac76f3a57bda\" href=\"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/RMP_23032026.pdf\">RMP_23032026<\/a><a href=\"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/RMP_23032026.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-d06fe0b0-57a8-4bac-9682-ac76f3a57bda\">Download PDF<\/a><\/div>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>Hoy 23 de Marzo, ingres\u00f3 560.0 TM de recursos hidrobiol\u00f3gicos a los mercados mayoristas de Lima (Villa Mar\u00eda del Triunfo) y Callao (Ventanilla); siendo 6.4% superior al abastecimiento de ayer. Entre las especies con mayor ingreso el d\u00eda de hoy fueron: Jurel, Bonito y Pota.Asimismo, ingresaron 378.6 TM de recursos hidrobiol\u00f3gicos a los mercados mayoristas &#8230; <a title=\"Report: Daily supply of hydrobiological resources. Wholesale Fish Markets 23-03-2026\" class=\"read-more\" href=\"https:\/\/www.producempresarial.pe\/en\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/\" aria-label=\"Read more about Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026\">Read more<\/a><\/p>","protected":false},"author":1,"featured_media":29871,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[262],"tags":[],"class_list":["post-29869","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artesanal-reportes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026 - Observatorio PRODUCEmpresarial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.producempresarial.pe\/en\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026 - Observatorio PRODUCEmpresarial\" \/>\n<meta property=\"og:description\" content=\"Hoy 23 de Marzo, ingres\u00f3 560.0 TM de recursos hidrobiol\u00f3gicos a los mercados mayoristas de Lima (Villa Mar\u00eda del Triunfo) y Callao (Ventanilla); siendo 6.4% superior al abastecimiento de ayer. Entre las especies con mayor ingreso el d\u00eda de hoy fueron: Jurel, Bonito y Pota.Asimismo, ingresaron 378.6 TM de recursos hidrobiol\u00f3gicos a los mercados mayoristas ... Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.producempresarial.pe\/en\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/\" \/>\n<meta property=\"og:site_name\" content=\"Observatorio PRODUCEmpresarial\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-25T14:55:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-13T19:57:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/mp23032026.png\" \/>\n\t<meta property=\"og:image:width\" content=\"645\" \/>\n\t<meta property=\"og:image:height\" content=\"858\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.producempresarial.pe\/#\/schema\/person\/6e13e1f2f8fc108ce3789cbdb23a5d21\"},\"headline\":\"Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026\",\"datePublished\":\"2026-03-25T14:55:22+00:00\",\"dateModified\":\"2026-04-13T19:57:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/\"},\"wordCount\":86,\"publisher\":{\"@id\":\"https:\/\/www.producempresarial.pe\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/mp23032026.png\",\"articleSection\":[\"Reportes Coyunturales\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/\",\"url\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/\",\"name\":\"Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026 - Observatorio PRODUCEmpresarial\",\"isPartOf\":{\"@id\":\"https:\/\/www.producempresarial.pe\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/mp23032026.png\",\"datePublished\":\"2026-03-25T14:55:22+00:00\",\"dateModified\":\"2026-04-13T19:57:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#primaryimage\",\"url\":\"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/mp23032026.png\",\"contentUrl\":\"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/mp23032026.png\",\"width\":645,\"height\":858},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.producempresarial.pe\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.producempresarial.pe\/#website\",\"url\":\"https:\/\/www.producempresarial.pe\/\",\"name\":\"Observatorio PRODUCEmpresarial\",\"description\":\"Herramienta estrat\u00e9gica que integra y genera peri\u00f3dicamente evidencia y an\u00e1lisis sobre el desempe\u00f1o productivo del sector empresarial, as\u00ed como contribuye en la difusi\u00f3n de informaci\u00f3n y documentos t\u00e9cnicos anal\u00edticos y especializados sobre el desempe\u00f1o de las empresas en el Per\u00fa.\",\"publisher\":{\"@id\":\"https:\/\/www.producempresarial.pe\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.producempresarial.pe\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.producempresarial.pe\/#organization\",\"name\":\"PRDOUCE\",\"url\":\"https:\/\/www.producempresarial.pe\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.producempresarial.pe\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2024\/02\/image-logo-share.png\",\"contentUrl\":\"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2024\/02\/image-logo-share.png\",\"width\":1200,\"height\":628,\"caption\":\"PRDOUCE\"},\"image\":{\"@id\":\"https:\/\/www.producempresarial.pe\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.producempresarial.pe\/#\/schema\/person\/6e13e1f2f8fc108ce3789cbdb23a5d21\",\"name\":\"admin\",\"sameAs\":[\"https:\/\/www.producempresarial.pe\"],\"url\":\"https:\/\/www.producempresarial.pe\/en\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026 - Observatorio PRODUCEmpresarial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.producempresarial.pe\/en\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/","og_locale":"en_US","og_type":"article","og_title":"Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026 - Observatorio PRODUCEmpresarial","og_description":"Hoy 23 de Marzo, ingres\u00f3 560.0 TM de recursos hidrobiol\u00f3gicos a los mercados mayoristas de Lima (Villa Mar\u00eda del Triunfo) y Callao (Ventanilla); siendo 6.4% superior al abastecimiento de ayer. Entre las especies con mayor ingreso el d\u00eda de hoy fueron: Jurel, Bonito y Pota.Asimismo, ingresaron 378.6 TM de recursos hidrobiol\u00f3gicos a los mercados mayoristas ... Read more","og_url":"https:\/\/www.producempresarial.pe\/en\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/","og_site_name":"Observatorio PRODUCEmpresarial","article_published_time":"2026-03-25T14:55:22+00:00","article_modified_time":"2026-04-13T19:57:54+00:00","og_image":[{"width":645,"height":858,"url":"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/mp23032026.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written por":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#article","isPartOf":{"@id":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/"},"author":{"name":"admin","@id":"https:\/\/www.producempresarial.pe\/#\/schema\/person\/6e13e1f2f8fc108ce3789cbdb23a5d21"},"headline":"Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026","datePublished":"2026-03-25T14:55:22+00:00","dateModified":"2026-04-13T19:57:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/"},"wordCount":86,"publisher":{"@id":"https:\/\/www.producempresarial.pe\/#organization"},"image":{"@id":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/mp23032026.png","articleSection":["Reportes Coyunturales"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/","url":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/","name":"Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026 - Observatorio PRODUCEmpresarial","isPartOf":{"@id":"https:\/\/www.producempresarial.pe\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#primaryimage"},"image":{"@id":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#primaryimage"},"thumbnailUrl":"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/mp23032026.png","datePublished":"2026-03-25T14:55:22+00:00","dateModified":"2026-04-13T19:57:54+00:00","breadcrumb":{"@id":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#primaryimage","url":"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/mp23032026.png","contentUrl":"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2026\/03\/mp23032026.png","width":645,"height":858},{"@type":"BreadcrumbList","@id":"https:\/\/www.producempresarial.pe\/reporte-abastecimiento-diario-de-recursos-hidrobiologicos-mercados-mayoristas-pesqueros-23-03-2025\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.producempresarial.pe\/"},{"@type":"ListItem","position":2,"name":"Reporte: Abastecimiento diario de recursos hidrobiol\u00f3gicos. Mercados mayoristas pesqueros 23-03-2026"}]},{"@type":"WebSite","@id":"https:\/\/www.producempresarial.pe\/#website","url":"https:\/\/www.producempresarial.pe\/","name":"PRODUCEmpresarial Observatory","description":"Herramienta estrat\u00e9gica que integra y genera peri\u00f3dicamente evidencia y an\u00e1lisis sobre el desempe\u00f1o productivo del sector empresarial, as\u00ed como contribuye en la difusi\u00f3n de informaci\u00f3n y documentos t\u00e9cnicos anal\u00edticos y especializados sobre el desempe\u00f1o de las empresas en el Per\u00fa.","publisher":{"@id":"https:\/\/www.producempresarial.pe\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.producempresarial.pe\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.producempresarial.pe\/#organization","name":"PRDOUCE","url":"https:\/\/www.producempresarial.pe\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.producempresarial.pe\/#\/schema\/logo\/image\/","url":"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2024\/02\/image-logo-share.png","contentUrl":"https:\/\/www.producempresarial.pe\/wp-content\/uploads\/2024\/02\/image-logo-share.png","width":1200,"height":628,"caption":"PRDOUCE"},"image":{"@id":"https:\/\/www.producempresarial.pe\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.producempresarial.pe\/#\/schema\/person\/6e13e1f2f8fc108ce3789cbdb23a5d21","name":"admin","sameAs":["https:\/\/www.producempresarial.pe"],"url":"https:\/\/www.producempresarial.pe\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/posts\/29869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/comments?post=29869"}],"version-history":[{"count":2,"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/posts\/29869\/revisions"}],"predecessor-version":[{"id":30144,"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/posts\/29869\/revisions\/30144"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/media\/29871"}],"wp:attachment":[{"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/media?parent=29869"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/categories?post=29869"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.producempresarial.pe\/en\/wp-json\/wp\/v2\/tags?post=29869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}